{"id":8011,"count":1,"description":"","link":"https:\/\/khannaandassociates.com\/blog\/tag\/cross-border-trade-lawyers-india\/","name":"cross-border trade lawyers India","slug":"cross-border-trade-lawyers-india","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/khannaandassociates.com\/blog\/wp-json\/wp\/v2\/tags\/8011"}],"collection":[{"href":"https:\/\/khannaandassociates.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/khannaandassociates.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/khannaandassociates.com\/blog\/wp-json\/wp\/v2\/posts?tags=8011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}